{"id":656,"date":"2022-04-08T10:35:20","date_gmt":"2022-04-08T02:35:20","guid":{"rendered":"https:\/\/www.universalchain.net\/?post_type=products&#038;p=656"},"modified":"2024-08-19T00:02:05","modified_gmt":"2024-08-18T16:02:05","slug":"trencher-chains","status":"publish","type":"products","link":"https:\/\/www.universalchain.net\/de\/products\/trencher-chains\/","title":{"rendered":"Ketten f\u00fcr Grabenfr\u00e4sen"},"content":{"rendered":"<p>Die Grabenfr\u00e4senkette ist mit einem Spezialschneider fester Breite an der Grundkette ausgestattet, der die Rillen kontinuierlich ausschneiden kann. Haupts\u00e4chlich verwendet in Milit\u00e4r, Kommunikation, Landwirtschaft und anderen Gelegenheiten. Die Kette hat die Eigenschaften Schlagfestigkeit und Verschlei\u00dffestigkeit.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Grabenfr\u00e4senkette ist mit einem Spezialschneider fester Breite an der Grundkette ausgestattet, der die Rillen kontinuierlich ausschneiden kann. Haupts\u00e4chlich verwendet in Milit\u00e4r, Kommunikation, Landwirtschaft und anderen Gelegenheiten. Die Kette hat die Eigenschaften Schlagfestigkeit und Verschlei\u00dffestigkeit.<\/p>","protected":false},"featured_media":657,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product":[20,24],"class_list":["post-656","products","type-products","status-publish","has-post-thumbnail","hentry","product-engineering-chains","product-trencher-chains"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trencher chains<\/title>\n<meta name=\"description\" content=\"Trencher chains - Professional Manufacturer of Chain Industrial - Universal Transmission\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.universalchain.net\/de\/products\/trencher-chains\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trencher chains\" \/>\n<meta property=\"og:description\" content=\"Trencher chains - Professional Manufacturer of Chain Industrial - Universal Transmission\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.universalchain.net\/de\/products\/trencher-chains\/\" \/>\n<meta property=\"og:site_name\" content=\"Professional Manufacturer of Chain Industrial - Universal Transmission\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universalsunzhou\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-18T16:02:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/\u672a\u6807\u9898-1-20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/products\\\/trencher-chains\\\/\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/products\\\/trencher-chains\\\/\",\"name\":\"Trencher chains\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/products\\\/trencher-chains\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/products\\\/trencher-chains\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/\u672a\u6807\u9898-1-20.jpg\",\"datePublished\":\"2022-04-08T02:35:20+00:00\",\"dateModified\":\"2024-08-18T16:02:05+00:00\",\"description\":\"Trencher chains - Professional Manufacturer of Chain Industrial - Universal Transmission\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/products\\\/trencher-chains\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.universalchain.net\\\/products\\\/trencher-chains\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/products\\\/trencher-chains\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/\u672a\u6807\u9898-1-20.jpg\",\"contentUrl\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/\u672a\u6807\u9898-1-20.jpg\",\"width\":512,\"height\":512,\"caption\":\"Trencher chains\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/products\\\/trencher-chains\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.universalchain.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product\",\"item\":\"https:\\\/\\\/www.universalchain.net\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trencher chains\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#website\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/\",\"name\":\"Professional Manufacturer of Chain Industrial - Universal Transmission\",\"description\":\"Leading Chain Transmission Manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#organization\"},\"alternateName\":\"Universal Chains\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.universalchain.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#organization\",\"name\":\"Universal Chains\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Stainless-Steel-Chain-\u4e0d\u9508\u94a2\u94fe.png\",\"contentUrl\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Stainless-Steel-Chain-\u4e0d\u9508\u94a2\u94fe.png\",\"width\":512,\"height\":388,\"caption\":\"Universal Chains\"},\"image\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universalsunzhou\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ketten f\u00fcr Grabenfr\u00e4sen","description":"Grabenfr\u00e4senketten \u2013 Professioneller Hersteller von Industrieketten \u2013 Universal-Getriebe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.universalchain.net\/de\/products\/trencher-chains\/","og_locale":"de_DE","og_type":"article","og_title":"Trencher chains","og_description":"Trencher chains - Professional Manufacturer of Chain Industrial - Universal Transmission","og_url":"https:\/\/www.universalchain.net\/de\/products\/trencher-chains\/","og_site_name":"Professional Manufacturer of Chain Industrial - Universal Transmission","article_publisher":"https:\/\/www.facebook.com\/universalsunzhou","article_modified_time":"2024-08-18T16:02:05+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/\u672a\u6807\u9898-1-20.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.universalchain.net\/products\/trencher-chains\/","url":"https:\/\/www.universalchain.net\/products\/trencher-chains\/","name":"Ketten f\u00fcr Grabenfr\u00e4sen","isPartOf":{"@id":"https:\/\/www.universalchain.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.universalchain.net\/products\/trencher-chains\/#primaryimage"},"image":{"@id":"https:\/\/www.universalchain.net\/products\/trencher-chains\/#primaryimage"},"thumbnailUrl":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/\u672a\u6807\u9898-1-20.jpg","datePublished":"2022-04-08T02:35:20+00:00","dateModified":"2024-08-18T16:02:05+00:00","description":"Grabenfr\u00e4senketten \u2013 Professioneller Hersteller von Industrieketten \u2013 Universal-Getriebe","breadcrumb":{"@id":"https:\/\/www.universalchain.net\/products\/trencher-chains\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.universalchain.net\/products\/trencher-chains\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.universalchain.net\/products\/trencher-chains\/#primaryimage","url":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/\u672a\u6807\u9898-1-20.jpg","contentUrl":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/\u672a\u6807\u9898-1-20.jpg","width":512,"height":512,"caption":"Trencher chains"},{"@type":"BreadcrumbList","@id":"https:\/\/www.universalchain.net\/products\/trencher-chains\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.universalchain.net\/"},{"@type":"ListItem","position":2,"name":"Product","item":"https:\/\/www.universalchain.net\/products\/"},{"@type":"ListItem","position":3,"name":"Trencher chains"}]},{"@type":"WebSite","@id":"https:\/\/www.universalchain.net\/#website","url":"https:\/\/www.universalchain.net\/","name":"Professioneller Hersteller von Industrieketten \u2013 Universal-Getriebe","description":"F\u00fchrender Hersteller von Kettengetrieben","publisher":{"@id":"https:\/\/www.universalchain.net\/#organization"},"alternateName":"Universal Chains","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.universalchain.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.universalchain.net\/#organization","name":"Universal-Ketten","url":"https:\/\/www.universalchain.net\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.universalchain.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/03\/Stainless-Steel-Chain-\u4e0d\u9508\u94a2\u94fe.png","contentUrl":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/03\/Stainless-Steel-Chain-\u4e0d\u9508\u94a2\u94fe.png","width":512,"height":388,"caption":"Universal Chains"},"image":{"@id":"https:\/\/www.universalchain.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universalsunzhou"]}]}},"_links":{"self":[{"href":"https:\/\/www.universalchain.net\/de\/wp-json\/wp\/v2\/products\/656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.universalchain.net\/de\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.universalchain.net\/de\/wp-json\/wp\/v2\/types\/products"}],"replies":[{"embeddable":true,"href":"https:\/\/www.universalchain.net\/de\/wp-json\/wp\/v2\/comments?post=656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.universalchain.net\/de\/wp-json\/wp\/v2\/media\/657"}],"wp:attachment":[{"href":"https:\/\/www.universalchain.net\/de\/wp-json\/wp\/v2\/media?parent=656"}],"wp:term":[{"taxonomy":"product","embeddable":true,"href":"https:\/\/www.universalchain.net\/de\/wp-json\/wp\/v2\/product?post=656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}