{"id":911,"date":"2022-04-29T18:23:06","date_gmt":"2022-04-29T10:23:06","guid":{"rendered":"https:\/\/www.universalchain.net\/?p=911"},"modified":"2022-04-29T18:23:08","modified_gmt":"2022-04-29T10:23:08","slug":"where-do-we-use-chain-drive","status":"publish","type":"post","link":"https:\/\/www.universalchain.net\/pt\/blogs\/where-do-we-use-chain-drive\/","title":{"rendered":"Onde usamos acionamento por corrente?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Uma transmiss\u00e3o por corrente \u00e9 um m\u00e9todo simples de atua\u00e7\u00e3o linear. \u00c9 amplamente utilizado em m\u00e1quinas industriais. A transmiss\u00e3o por corrente t\u00edpica consiste em uma corrente conectada a uma roda dentada. Esta \u00e9 a parte motriz e se conecta a outras partes m\u00f3veis do sistema. Essas unidades podem ser bastante dur\u00e1veis e suportar altas velocidades.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 uma maneira eficiente de transmitir energia. Possui baixos requisitos de manuten\u00e7\u00e3o e pode operar mesmo em condi\u00e7\u00f5es \u00famidas, o que \u00e9 uma caracter\u00edstica importante dos equipamentos industriais. Outra vantagem de usar um acionamento por corrente \u00e9 que ele pode suportar altas temperaturas e umidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma transmiss\u00e3o por corrente pode ser usada em muitas aplica\u00e7\u00f5es mec\u00e2nicas. \u00c9 melhor para aplica\u00e7\u00f5es onde \u00e9 necess\u00e1rio movimentar grandes cargas com alto torque e sem deslizamento. Da mesma forma, os acionamentos por corrente s\u00e3o usados em m\u00e1quinas agr\u00edcolas, compressores e fornos que possuem alta velocidade de rota\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existem muitos usos e aplica\u00e7\u00f5es da transmiss\u00e3o por corrente. Se voc\u00ea quiser saber onde as correntes s\u00e3o usadas, continue lendo este artigo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Onde usamos acionamento por corrente?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ao comparar o desempenho dos acionamentos por correia e corrente, as vantagens do acionamento por corrente s\u00e3o \u00f3bvias. Por esse motivo, tem muitas aplica\u00e7\u00f5es. Aqui est\u00e3o alguns usos e aplica\u00e7\u00f5es comuns de acionamentos por corrente.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Bicicleta<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A transmiss\u00e3o por corrente \u00e9 usada em bicicletas. Um driver de corrente de bicicleta \u00e9 um dispositivo mec\u00e2nico usado no ciclismo. Funciona distribuindo a pot\u00eancia entre os pedais e as rodas dentadas da roda complementar. As duas rodas dentadas s\u00e3o unidas lado a lado por uma corrente e trabalham juntas para transmitir pot\u00eancia e torque. Conforme voc\u00ea move o pedal, a corrente se move, o que gira a roda dentada, e a roda pode fazer com que a bicicleta se mova para frente.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Autom\u00f3veis<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Uma transmiss\u00e3o por corrente \u00e9 o mecanismo de transmiss\u00e3o de energia usado em ve\u00edculos. A maioria dos ve\u00edculos usa transmiss\u00e3o por corrente para funcionar. Ao contr\u00e1rio do acionamento por correia ou corda, a taxa de velocidade de um acionamento por corrente \u00e9 constante. As engrenagens de entrada e sa\u00edda s\u00e3o engrenadas e se movem na mesma dire\u00e7\u00e3o. As correntes ovais ajudam os ve\u00edculos a se moverem transferindo energia.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>motocicletas<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Acionamentos por corrente s\u00e3o comuns em motocicletas. Em uma motocicleta, uma corrente \u00e9 conectada \u00e0s duas rodas dentadas, o que ajuda na movimenta\u00e7\u00e3o da motocicleta. Ele usa o mesmo mecanismo de uma bicicleta para se mover. No entanto, em vez do pedal, a motocicleta \u00e9 movida pelo motor. \u00c0 medida que o motor arranca, a corrente move-se, transferindo assim a pot\u00eancia para a roda traseira e fazendo com que a moto se mova.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Maquinaria agr\u00edcola<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">As m\u00e1quinas agr\u00edcolas usam uma transmiss\u00e3o por corrente para v\u00e1rias finalidades, desde a colheita de colheitas at\u00e9 a limpeza e muitas outras coisas. A maioria das m\u00e1quinas agr\u00edcolas usa transmiss\u00e3o por corrente. Este dispositivo requer uma roda dentada com passo de 30 a 50 vezes o passo da corrente. A roda dentada tamb\u00e9m deve ter um arco m\u00ednimo de contato de 120 graus na roda dentada menor para funcionar corretamente. A corrente de rolos \u00e9 usada nesses tipos de m\u00e1quinas para faz\u00ea-los funcionar.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>M\u00e1quinas para trabalhar madeira<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Uma transmiss\u00e3o por corrente \u00e9 um dispositivo que transmite energia de uma m\u00e1quina para outra. \u00c9 comumente usado em m\u00e1quinas pesadas para girar tambores rotativos. Tamb\u00e9m \u00e9 usado para conduzir grandes guindastes off-road e draglines. Essas m\u00e1quinas s\u00e3o equipadas com grandes motores para acion\u00e1-las. Eles est\u00e3o dispon\u00edveis em diferentes tipos e podem ser encontrados em diferentes tipos de m\u00e1quinas para trabalhar madeira.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Equipamento de Manuseio de Materiais<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A transmiss\u00e3o por corrente \u00e9 um componente importante do equipamento de manuseio de materiais. \u00c9 usado na movimenta\u00e7\u00e3o de correntes. Os elos s\u00e3o feitos de metal e s\u00e3o r\u00edgidos, mas possuem juntas de pinos que proporcionam flexibilidade no envolvimento das rodas. As rodas acionadas e motrizes t\u00eam dentes que se encaixam em um recesso nos elos da corrente. Os acionamentos por corrente s\u00e3o frequentemente usados para mover materiais pesados, bem como materiais mais leves, de um lugar para outro em um transportador.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Constru\u00e7\u00e3o civil<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Uma transmiss\u00e3o por corrente \u00e9 um sistema de transmiss\u00e3o de energia mec\u00e2nica. As correntes s\u00e3o compostas por uma s\u00e9rie cont\u00ednua de elos. A corrente \u00e9 girada por engrenagens dentadas. Este tipo de acionador de corrente \u00e9 frequentemente usado em m\u00e1quinas pesadas e sistemas de transporte. \u00c9 usado na constru\u00e7\u00e3o civil para levantar e i\u00e7ar itens pesados e mov\u00ea-los de um lugar para outro.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Plataformas de Perfura\u00e7\u00e3o de Po\u00e7os de Petr\u00f3leo<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Uma transmiss\u00e3o por corrente \u00e9 um equipamento usado na perfura\u00e7\u00e3o de po\u00e7os de petr\u00f3leo. Este dispositivo \u00e9 usado para conduzir uma coluna de perfura\u00e7\u00e3o atrav\u00e9s de um furo profundo. O perfurador puxa a corrente de uma ponta da corda e a transforma no carretel. O carretel \u00e9 aparafusado na junta, que \u00e9 pendurada em cunhas. O uso de correntes girat\u00f3rias foi descontinuado pela maioria dos empreiteiros de plataformas. Essas ferramentas ainda est\u00e3o dispon\u00edveis em algumas plataformas.<\/p>","protected":false},"excerpt":{"rendered":"<p>A chain drive is a simple method of linear actuation. It is widely used in industrial machinery. The typical chain drive consists of a chain connected to a sprocket. This is the driving part, and it connects to other moving parts of the system. These drives can be quite durable and withstand high speeds.&nbsp; It [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Where Do We Use Chain Drive? - Professional Manufacturer of Chain Industrial - Universal Transmission<\/title>\n<meta name=\"description\" content=\"A chain drive is a simple method of linear actuation. It is widely used in industrial machinery. The typical chain drive consists of a chain connected to a sprocket.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.universalchain.net\/pt\/blogs\/where-do-we-use-chain-drive\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Where Do We Use Chain Drive? - Professional Manufacturer of Chain Industrial - Universal Transmission\" \/>\n<meta property=\"og:description\" content=\"A chain drive is a simple method of linear actuation. It is widely used in industrial machinery. The typical chain drive consists of a chain connected to a sprocket.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.universalchain.net\/pt\/blogs\/where-do-we-use-chain-drive\/\" \/>\n<meta property=\"og:site_name\" content=\"Professional Manufacturer of Chain Industrial - Universal Transmission\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universalsunzhou\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-29T10:23:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-29T10:23:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/chain8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#\\\/schema\\\/person\\\/b3c3ef5ad752ffb017c67adba7eb9eab\"},\"headline\":\"Where Do We Use Chain Drive?\",\"datePublished\":\"2022-04-29T10:23:06+00:00\",\"dateModified\":\"2022-04-29T10:23:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/\"},\"wordCount\":784,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/chain8.jpg\",\"articleSection\":[\"Blogs\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/\",\"name\":\"Where Do We Use Chain Drive? - Professional Manufacturer of Chain Industrial - Universal Transmission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/chain8.jpg\",\"datePublished\":\"2022-04-29T10:23:06+00:00\",\"dateModified\":\"2022-04-29T10:23:08+00:00\",\"description\":\"A chain drive is a simple method of linear actuation. It is widely used in industrial machinery. The typical chain drive consists of a chain connected to a sprocket.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/chain8.jpg\",\"contentUrl\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/chain8.jpg\",\"width\":612,\"height\":408,\"caption\":\"Broken driving roller chain. Parts of destroyed industrial chain\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/blogs\\\/where-do-we-use-chain-drive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.universalchain.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Where Do We Use Chain Drive?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#website\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/\",\"name\":\"Professional Manufacturer of Chain Industrial - Universal Transmission\",\"description\":\"Leading Chain Transmission Manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#organization\"},\"alternateName\":\"Universal Chains\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.universalchain.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#organization\",\"name\":\"Universal Chains\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Stainless-Steel-Chain-\u4e0d\u9508\u94a2\u94fe.png\",\"contentUrl\":\"https:\\\/\\\/www.universalchain.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Stainless-Steel-Chain-\u4e0d\u9508\u94a2\u94fe.png\",\"width\":512,\"height\":388,\"caption\":\"Universal Chains\"},\"image\":{\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universalsunzhou\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.universalchain.net\\\/#\\\/schema\\\/person\\\/b3c3ef5ad752ffb017c67adba7eb9eab\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60fe2c71042a68f46207d3024e5a0e23c5c245eecfa69948722026dd0d9ba25f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60fe2c71042a68f46207d3024e5a0e23c5c245eecfa69948722026dd0d9ba25f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60fe2c71042a68f46207d3024e5a0e23c5c245eecfa69948722026dd0d9ba25f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.universalchain.net\"],\"url\":\"https:\\\/\\\/www.universalchain.net\\\/pt\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Onde usamos a transmiss\u00e3o por corrente? - Fabricante Profissional de Corrente Industrial - Transmiss\u00e3o Universal","description":"Uma transmiss\u00e3o por corrente \u00e9 um m\u00e9todo simples de atua\u00e7\u00e3o linear. \u00c9 amplamente utilizado em m\u00e1quinas industriais. A transmiss\u00e3o por corrente t\u00edpica consiste em uma corrente conectada a uma roda dentada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.universalchain.net\/pt\/blogs\/where-do-we-use-chain-drive\/","og_locale":"pt_BR","og_type":"article","og_title":"Where Do We Use Chain Drive? - Professional Manufacturer of Chain Industrial - Universal Transmission","og_description":"A chain drive is a simple method of linear actuation. It is widely used in industrial machinery. The typical chain drive consists of a chain connected to a sprocket.","og_url":"https:\/\/www.universalchain.net\/pt\/blogs\/where-do-we-use-chain-drive\/","og_site_name":"Professional Manufacturer of Chain Industrial - Universal Transmission","article_publisher":"https:\/\/www.facebook.com\/universalsunzhou","article_published_time":"2022-04-29T10:23:06+00:00","article_modified_time":"2022-04-29T10:23:08+00:00","og_image":[{"width":612,"height":408,"url":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/chain8.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/#article","isPartOf":{"@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/"},"author":{"name":"admin","@id":"https:\/\/www.universalchain.net\/#\/schema\/person\/b3c3ef5ad752ffb017c67adba7eb9eab"},"headline":"Where Do We Use Chain Drive?","datePublished":"2022-04-29T10:23:06+00:00","dateModified":"2022-04-29T10:23:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/"},"wordCount":784,"commentCount":0,"publisher":{"@id":"https:\/\/www.universalchain.net\/#organization"},"image":{"@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/chain8.jpg","articleSection":["Blogs"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/","url":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/","name":"Onde usamos a transmiss\u00e3o por corrente? - Fabricante Profissional de Corrente Industrial - Transmiss\u00e3o Universal","isPartOf":{"@id":"https:\/\/www.universalchain.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/#primaryimage"},"image":{"@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/chain8.jpg","datePublished":"2022-04-29T10:23:06+00:00","dateModified":"2022-04-29T10:23:08+00:00","description":"Uma transmiss\u00e3o por corrente \u00e9 um m\u00e9todo simples de atua\u00e7\u00e3o linear. \u00c9 amplamente utilizado em m\u00e1quinas industriais. A transmiss\u00e3o por corrente t\u00edpica consiste em uma corrente conectada a uma roda dentada.","breadcrumb":{"@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/#primaryimage","url":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/chain8.jpg","contentUrl":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/04\/chain8.jpg","width":612,"height":408,"caption":"Broken driving roller chain. Parts of destroyed industrial chain"},{"@type":"BreadcrumbList","@id":"https:\/\/www.universalchain.net\/blogs\/where-do-we-use-chain-drive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.universalchain.net\/"},{"@type":"ListItem","position":2,"name":"Where Do We Use Chain Drive?"}]},{"@type":"WebSite","@id":"https:\/\/www.universalchain.net\/#website","url":"https:\/\/www.universalchain.net\/","name":"Fabricante Profissional de Corrente Industrial - Transmiss\u00e3o Universal","description":"Fabricante l\u00edder de transmiss\u00e3o de corrente","publisher":{"@id":"https:\/\/www.universalchain.net\/#organization"},"alternateName":"Universal Chains","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.universalchain.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.universalchain.net\/#organization","name":"Correntes Universal","url":"https:\/\/www.universalchain.net\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.universalchain.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/03\/Stainless-Steel-Chain-\u4e0d\u9508\u94a2\u94fe.png","contentUrl":"https:\/\/www.universalchain.net\/wp-content\/uploads\/2022\/03\/Stainless-Steel-Chain-\u4e0d\u9508\u94a2\u94fe.png","width":512,"height":388,"caption":"Universal Chains"},"image":{"@id":"https:\/\/www.universalchain.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universalsunzhou"]},{"@type":"Person","@id":"https:\/\/www.universalchain.net\/#\/schema\/person\/b3c3ef5ad752ffb017c67adba7eb9eab","name":"administrador","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/60fe2c71042a68f46207d3024e5a0e23c5c245eecfa69948722026dd0d9ba25f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/60fe2c71042a68f46207d3024e5a0e23c5c245eecfa69948722026dd0d9ba25f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/60fe2c71042a68f46207d3024e5a0e23c5c245eecfa69948722026dd0d9ba25f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.universalchain.net"],"url":"https:\/\/www.universalchain.net\/pt\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/posts\/911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/comments?post=911"}],"version-history":[{"count":0,"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/posts\/911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/media\/827"}],"wp:attachment":[{"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/media?parent=911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/categories?post=911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.universalchain.net\/pt\/wp-json\/wp\/v2\/tags?post=911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}